{"id":12343,"date":"2021-11-29T14:40:26","date_gmt":"2021-11-29T14:40:26","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=12343"},"modified":"2021-11-29T14:40:26","modified_gmt":"2021-11-29T14:40:26","slug":"conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/","title":{"rendered":"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud"},"content":{"rendered":"\n<p style=\"text-align: justify;\">Una de las razones por las que la investigaci\u00f3n en salud es importante es para estudiar la eficacia y seguridad de un medicamento. Algunos medicamentos pueden funcionar durante los ensayos cl\u00ednicos, pero pueden no funcionar en la pr\u00e1ctica por factores como la raza, el origen \u00e9tnico, la edad, el g\u00e9nero, entre otros. Aunque conocemos la importancia de la investigaci\u00f3n en salud, a menudo nos hacemos preguntas como: &#8220;\u00bfPor qu\u00e9 debo participar en la investigaci\u00f3n en salud? \u00bfCu\u00e1les son los resultados posibles de mi participaci\u00f3n? \u00bfHar\u00e9 una diferencia?&#8221; La verdad es que la investigaci\u00f3n en salud tiene como objetivo encontrar mejores formas de prevenir y tratar las enfermedades. La investigaci\u00f3n en salud es una forma importante de ayudar a mejorar la atenci\u00f3n m\u00e9dica y el tratamiento de las personas en todo el mundo.<\/p>\n<p style=\"text-align: justify;\">Un ejemplo de una iniciativa de investigaci\u00f3n en salud es el<a href=\"https:\/\/www.joinallofus.org\/es\/juntos\"> Programa de Investigaci\u00f3n Cient\u00edfica All of Us<\/a>, liderado por los Institutos Nacionales de la Salud, cuyo objetivo es ayudar a acelerar la investigaci\u00f3n en salud. Las personas que participen en este programa compartir\u00e1n informaci\u00f3n sobre su salud, sus h\u00e1bitos y su medio ambiente. Al buscar patrones, los investigadores podr\u00edan aprender m\u00e1s sobre lo que afecta la salud de las personas y, en el futuro, encontrar tratamientos o estrategias de prevenci\u00f3n de enfermedades.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, debido a la gran cantidad de desinformaci\u00f3n que existe, muchas personas desconocen los beneficios de la investigaci\u00f3n en salud e incluso tienen miedo de participar en esta importante iniciativa.<\/p>\n<p style=\"text-align: justify;\">\u00bfUsted puede distinguir entre los mitos y los hechos de la investigaci\u00f3n en salud? Conozca las respuestas sobre la investigaci\u00f3n en salud y el Programa Cient\u00edfico All of Us.<\/p>\n<p style=\"text-align: justify;\">\u2794<strong> MITO:<\/strong> La raza o el origen \u00e9tnico de los participantes en la investigaci\u00f3n en salud no es importante porque la medicina tiene el mismo efecto en todos.<br \/>\u2605 <strong>REALIDAD<\/strong>: El cuerpo de cada persona procesa los medicamentos de forma diferente, y la atenci\u00f3n m\u00e9dica que recibimos no deber\u00eda ser la misma para todos. Seg\u00fan la Oficina de Salud de las Minor\u00edas de los Estados Unidos, los adultos hispanos son 70% m\u00e1s propensos que los adultos blancos no hispanos de ser diagnosticados con diabetes y, adem\u00e1s, tienen 1.2 veces m\u00e1s probabilidades de ser obesos. Esto demuestra lo diferente que son las experiencias de salud de nuestra comunidad con respecto a otros grupos.<\/p>\n<p style=\"text-align: justify;\">\u2794 <strong>MITO:<\/strong> Hay suficientes personas que participan en la investigaci\u00f3n en salud, por lo que mi participaci\u00f3n no es necesaria. <br \/>\u2605 <strong>REALIDAD:<\/strong> Aunque los hispanos representan casi el 19% de la poblaci\u00f3n en los Estados Unidos, menos del 5% participa en ensayos cl\u00ednicos. \u00a1Necesitamos que m\u00e1s personas de nuestra comunidad participen! Cuantas m\u00e1s personas participen, los investigadores tendr\u00e1n una imagen m\u00e1s completa de la salud en nuestra comunidad.<\/p>\n<p style=\"text-align: justify;\">\u2794 <strong>MITO:<\/strong> Ser\u00e9 un conejillo de Indias.<br \/>\u2605<strong> REALIDAD:<\/strong> Hay muchos reglamentos estrictos para realizar ensayos cl\u00ednicos, y usted debe dar su consentimiento (estar de acuerdo) antes de participar. Si participa en el Programa Cient\u00edfico All of Us, los participantes son considerados colaboradores. Con All of Us, los participantes aportan al programa con sus sugerencias y a la vez, obtienen informaci\u00f3n sobre s\u00ed mismos.<\/p>\n<p style=\"text-align: justify;\">\u2794<strong> MITO<\/strong>: Participar en la investigaci\u00f3n en salud no tiene ning\u00fan beneficio.<br \/>\u2605<strong> REALIDAD:<\/strong> Las investigaciones en salud ayudan a los investigadores a encontrar las mejores maneras para mantener sanas a las personas y a crear mejores tratamientos. Participar en la investigaci\u00f3n puede mejorar la salud en su comunidad y en las generaciones futuras, pero el Programa Cient\u00edfico All of Us tambi\u00e9n tiene beneficios espec\u00edficos para usted. Usted puede obtener informaci\u00f3n sobre su salud, incluyendo de gen\u00e9tica y del ADN. Estos resultados pueden incluir informaci\u00f3n sobre la ascendencia (de d\u00f3nde proviene su familia), caracter\u00edsticas (por ejemplo, si usted puede digerir la leche), si tiene un mayor riesgo de desarrollar algunas enfermedades y c\u00f3mo puede responder su cuerpo a ciertos medicamentos. Esto puede ayudarle a tomar decisiones m\u00e1s informadas sobre su salud.<\/p>\n<p style=\"text-align: justify;\">\u2794<strong> MITO:<\/strong> Mis datos de salud e informaci\u00f3n personal ser\u00e1n compartidos con otras agencias gubernamentales.<br \/>\u2605 <strong>REALIDAD:<\/strong> Estos son algunos datos sobre el Programa Cient\u00edfico All of Us:<br \/>\u25cb El programa no le pregunta sobre su ciudadan\u00eda o estatus de inmigraci\u00f3n.<br \/>\u25cb El programa no puede compartir su informaci\u00f3n con otras agencias gubernamentales.<br \/>\u25cb Participar en el programa no afectar\u00e1 su estatus de inmigraci\u00f3n.<br \/>\u25cb Su informaci\u00f3n m\u00e9dica o personal nunca ser\u00e1 compartida con un futuro empleador.<br \/>\u25cb Legalmente, el programa no puede proporcionar su informaci\u00f3n a nadie fuera del programa.<br \/>\u25cb La informaci\u00f3n compartida con el programa no es admisible en un tribunal o corte de justicia, lo que significa que no puede ser utilizada en su contra en un entorno legal.<\/p>\n<p style=\"text-align: justify;\">\u2794 <strong>MITO:<\/strong> Las personas saludables no necesitan participar en la investigaci\u00f3n en salud. Solo las personas muy enfermas participan en estudios m\u00e9dicos.<br \/>\u2605 <strong>REALIDAD:<\/strong> Con el Programa Cient\u012bfico All of Us, usted puede participar en la investigaci\u00f3n en salud sin importar cu\u00e1ntas o qu\u00e9 tipo de enfermedades padezca. La inscripci\u00f3n en All of Us est\u00e1 abierta a todos los adultos elegibles (mayores de 18 a\u00f1os) que viven en los Estados Unidos. Las personas de cualquier raza, etnia, sexo, g\u00e9nero y orientaci\u00f3n sexual son bienvenidas. Usted puede estar sano o padecer alguna enfermedad y aun as\u00ed participar en el programa.<\/p>\n<p style=\"text-align: justify;\">\u2794<strong> MITO:<\/strong> Necesito un seguro m\u00e9dico para participar en investigaciones en salud.<br \/>\u2605<strong> REALIDAD:<\/strong> Usted no necesita tener un seguro m\u00e9dico para participar en All of Us porque es un programa de investigaci\u00f3n, no de atenci\u00f3n m\u00e9dica.<\/p>\n<p style=\"text-align: justify;\">Participar en el Programa Cient\u00edfico All of Us le ofrece una serie de beneficios que contribuir\u00e1n a su salud y a la de toda la comunidad. Si est\u00e1 interesado en formar parte de All of Us, visite el sitio web de All of Us en <a href=\"https:\/\/www.joinallofus.org\/todosjuntos\">https:\/\/www.joinallofus.org\/todosjuntos<\/a> o llame al 844-842-2855.<\/p>\n<p style=\"text-align: center;\"><strong>\u00a1Forme parte del futuro de la salud!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":12344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[9,5],"tags":[],"class_list":["post-12343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-media-center"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud - NHCOA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T14:40:26+00:00\" \/>\n<meta name=\"author\" content=\"devs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"devs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/\"},\"author\":{\"name\":\"devs\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/f84200aebc533e406ad0d886224a7346\"},\"headline\":\"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud\",\"datePublished\":\"2021-11-29T14:40:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/\"},\"wordCount\":1044,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Blog\",\"Media Center\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/\",\"name\":\"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-11-29T14:40:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/f84200aebc533e406ad0d886224a7346\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/f84200aebc533e406ad0d886224a7346\",\"name\":\"devs\",\"sameAs\":[\"https:\\\/\\\/nhcoa.org\\\/es\"],\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/devs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/","og_locale":"en_US","og_type":"article","og_title":"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud - NHCOA","og_url":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/","og_site_name":"NHCOA","article_published_time":"2021-11-29T14:40:26+00:00","author":"devs","twitter_card":"summary_large_image","twitter_misc":{"Written by":"devs","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/"},"author":{"name":"devs","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/f84200aebc533e406ad0d886224a7346"},"headline":"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud","datePublished":"2021-11-29T14:40:26+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/"},"wordCount":1044,"commentCount":0,"image":{"@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#primaryimage"},"thumbnailUrl":"","articleSection":["Blog","Media Center"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/","url":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/","name":"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-11-29T14:40:26+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/f84200aebc533e406ad0d886224a7346"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/conozcamos-los-mitos-y-realidades-sobre-la-investigacion-en-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conozcamos los mitos y realidades sobre la investigaci\u00f3n en salud"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/f84200aebc533e406ad0d886224a7346","name":"devs","sameAs":["https:\/\/nhcoa.org\/es"],"url":"https:\/\/nhcoa.org\/es\/author\/devs\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=12343"}],"version-history":[{"count":0,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12343\/revisions"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=12343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=12343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=12343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}