{"id":12711,"date":"2021-12-22T01:06:00","date_gmt":"2021-12-22T01:06:00","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=12711"},"modified":"2022-07-19T19:59:59","modified_gmt":"2022-07-19T19:59:59","slug":"consumo-de-tabaco-en-la-comunidad-latina-2","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/","title":{"rendered":"Consumo de tabaco en la comunidad Latina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><\/p>\n\n\n<h3><strong>\u00bfSab\u00eda que el tabaco afecta gravemente la salud de los Latinos?<\/strong><\/h3>\n<h4>En esta edici\u00f3n, conversamos con la con la Dra. Lourdes Parry Gutierrez sobre la prevalencia del consumo tabaco dentro de la comunidad Hispana\/Latina y sus riesgos para la salud en fumadores activos y pasivos.<p><\/p>\n<p>En colaboraci\u00f3n con Campaign for Tobacco-Free Kids.<\/p>\n<\/h4>\n<h4><strong>Eche un vistazo al nuevo episodio:<\/strong><\/h4>\n<p><\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#CafecitoConNHCOA \u2615| Consumo de tabaco en la comunidad Latina\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/fZm_0xNH6ls?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u2615 \u00bfQu\u00e9 es Cafecito con NHCOA? <\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Es la primera serie web de NHCOA con la que se pretende conectar con el p\u00fablico de la organizaci\u00f3n y la comunidad hispana durante la pandemia de COVID-19. En este desarrollar\u00e1n temas actuales y de inter\u00e9s para los adultos mayores as\u00ed como para el p\u00fablico en general.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p> \u00bfSab\u00eda que el tabaco afecta gravemente la salud de los Latinos?\ud83d\ude2f<br \/>\nEn esta edici\u00f3n, conversamos con la con la Dra. Lourdes Parry&#8230;<\/p>\n","protected":false},"author":2,"featured_media":12881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[20],"tags":[],"class_list":["post-12711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafecito-con-nhcoa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consumo de tabaco en la comunidad Latina - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consumo de tabaco en la comunidad Latina - NHCOA\" \/>\n<meta property=\"og:description\" content=\"\u00bfSab\u00eda que el tabaco afecta gravemente la salud de los Latinos?\ud83d\ude2f En esta edici\u00f3n, conversamos con la con la Dra. Lourdes Parry...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-22T01:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-19T19:59:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/maxresdefault-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Consumo de tabaco en la comunidad Latina\",\"datePublished\":\"2021-12-22T01:06:00+00:00\",\"dateModified\":\"2022-07-19T19:59:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/\"},\"wordCount\":132,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/maxresdefault-16.jpg\",\"articleSection\":[\"Cafecito Con NHCOA\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/\",\"name\":\"Consumo de tabaco en la comunidad Latina - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/maxresdefault-16.jpg\",\"datePublished\":\"2021-12-22T01:06:00+00:00\",\"dateModified\":\"2022-07-19T19:59:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/consumo-de-tabaco-en-la-comunidad-latina-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consumo de tabaco en la comunidad Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consumo de tabaco en la comunidad Latina - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/","og_locale":"en_US","og_type":"article","og_title":"Consumo de tabaco en la comunidad Latina - NHCOA","og_description":"\u00bfSab\u00eda que el tabaco afecta gravemente la salud de los Latinos?\ud83d\ude2f En esta edici\u00f3n, conversamos con la con la Dra. Lourdes Parry...","og_url":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/","og_site_name":"NHCOA","article_published_time":"2021-12-22T01:06:00+00:00","article_modified_time":"2022-07-19T19:59:59+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/maxresdefault-16.jpg","type":"image\/jpeg"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Consumo de tabaco en la comunidad Latina","datePublished":"2021-12-22T01:06:00+00:00","dateModified":"2022-07-19T19:59:59+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/"},"wordCount":132,"image":{"@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/maxresdefault-16.jpg","articleSection":["Cafecito Con NHCOA"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/","url":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/","name":"Consumo de tabaco en la comunidad Latina - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/maxresdefault-16.jpg","datePublished":"2021-12-22T01:06:00+00:00","dateModified":"2022-07-19T19:59:59+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/consumo-de-tabaco-en-la-comunidad-latina-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Consumo de tabaco en la comunidad Latina"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=12711"}],"version-history":[{"count":5,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12711\/revisions"}],"predecessor-version":[{"id":12882,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12711\/revisions\/12882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/12881"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=12711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=12711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=12711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}