{"id":12735,"date":"2021-05-01T01:24:00","date_gmt":"2021-05-01T01:24:00","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=12735"},"modified":"2022-07-19T19:26:20","modified_gmt":"2022-07-19T19:26:20","slug":"osteoporosis-nhcoa","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/","title":{"rendered":"Osteoporosis"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><\/p>\n\n\n<h3><strong>\u00bfQu\u00e9 conoce sobre la osteoporosis?<\/strong><\/h3>\n<h4>En esta edici\u00f3n hablaremos sobre los s\u00edntomas de esta enfermedad y su prevalec\u00eda dentro de la comunidad latina.<\/h4>\n<h4><strong>Conozca m\u00e1s viendo el video:<\/strong><\/h4>\n<p><\/p>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#CafecitoconNHCOA: Osteoporosis | NHCOA\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/d6n2LWx66Mw?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u2615 \u00bfQu\u00e9 es Cafecito con NHCOA? <\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Es la primera serie web de NHCOA con la que se pretende conectar con el p\u00fablico de la organizaci\u00f3n y la comunidad hispana durante la pandemia de COVID-19. En este desarrollar\u00e1n temas actuales y de inter\u00e9s para los adultos mayores as\u00ed como para el p\u00fablico en general.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 conoce sobre la osteoporosis?\ud83e\uddb4<br \/>\nEn esta edici\u00f3n hablaremos sobre los s\u00edntomas de esta enfe&#8230;<\/p>\n","protected":false},"author":2,"featured_media":12869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[20],"tags":[],"class_list":["post-12735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafecito-con-nhcoa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Osteoporosis - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Osteoporosis - NHCOA\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 conoce sobre la osteoporosis?\ud83e\uddb4 En esta edici\u00f3n hablaremos sobre los s\u00edntomas de esta enfe...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-01T01:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-19T19:26:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/Osteoporosis-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Osteoporosis\",\"datePublished\":\"2021-05-01T01:24:00+00:00\",\"dateModified\":\"2022-07-19T19:26:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/\"},\"wordCount\":97,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Osteoporosis-.png\",\"articleSection\":[\"Cafecito Con NHCOA\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/\",\"name\":\"Osteoporosis - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Osteoporosis-.png\",\"datePublished\":\"2021-05-01T01:24:00+00:00\",\"dateModified\":\"2022-07-19T19:26:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/osteoporosis-nhcoa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Osteoporosis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Osteoporosis - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/","og_locale":"en_US","og_type":"article","og_title":"Osteoporosis - NHCOA","og_description":"\u00bfQu\u00e9 conoce sobre la osteoporosis?\ud83e\uddb4 En esta edici\u00f3n hablaremos sobre los s\u00edntomas de esta enfe...","og_url":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/","og_site_name":"NHCOA","article_published_time":"2021-05-01T01:24:00+00:00","article_modified_time":"2022-07-19T19:26:20+00:00","og_image":[{"width":1366,"height":768,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/Osteoporosis-.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Osteoporosis","datePublished":"2021-05-01T01:24:00+00:00","dateModified":"2022-07-19T19:26:20+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/"},"wordCount":97,"image":{"@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/Osteoporosis-.png","articleSection":["Cafecito Con NHCOA"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/","url":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/","name":"Osteoporosis - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/06\/Osteoporosis-.png","datePublished":"2021-05-01T01:24:00+00:00","dateModified":"2022-07-19T19:26:20+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/osteoporosis-nhcoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Osteoporosis"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=12735"}],"version-history":[{"count":4,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12735\/revisions"}],"predecessor-version":[{"id":12870,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/12735\/revisions\/12870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/12869"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=12735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=12735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=12735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}