{"id":13053,"date":"2022-09-28T14:18:30","date_gmt":"2022-09-28T14:18:30","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13053"},"modified":"2022-09-28T14:19:30","modified_gmt":"2022-09-28T14:19:30","slug":"celebrando-el-mes-de-la-herencia-hispana","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/","title":{"rendered":"Celebrando el Mes de la Herencia Hispana"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/09\/2-3-1024x683.png\" alt=\"\" class=\"wp-image-13049\" width=\"512\" height=\"342\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Por un mes, desde el&nbsp;15 de septiembre hasta el 15 de octubre, en Estados Unidos y en el mundo celebramos el <strong>Mes de la Herencia Hispan<\/strong>a o tambi\u00e9n llamada Herencia Latina.&nbsp;La celebraci\u00f3n comienza a mediados de mes, como un gui\u00f1o a los aniversarios de la independencia nacional de varios pa\u00edses latinoamericanos: Costa Rica, El Salvador, Guatemala, Honduras y Nicaragua, que reconocen el 15 de septiembre como la fecha de su independencia.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Le sigue el D\u00eda de la Independencia de M\u00e9xico, el 16 de septiembre, y el de Chile, el 18 de septiembre. Otra fecha importante que se celebra dentro de este periodo de 30 d\u00edas es el D\u00eda de la Resistencia Ind\u00edgena o D\u00eda de la Hispanidad, que se conmemora el 12 de octubre.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-black-color has-text-color is-layout-flow wp-block-quote-is-layout-flow\" style=\"font-size:15px\"><p><strong>El Mes de la Herencia Hispana se ha convertido en una gran celebraci\u00f3n en Estados Unidos. Es una celebraci\u00f3n nacional para honrar la historia, la cultura y la influencia de generaciones pasadas que vinieron de Espa\u00f1a, M\u00e9xico, el Caribe y Am\u00e9rica Central y del Sur. Durante m\u00e1s de 40 a\u00f1os, los hispanos de todo el pa\u00eds conmemoran este mes con orgullo y alegr\u00eda, adem\u00e1s de que destacan la importancia de la diversidad.<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">La celebraci\u00f3n comenz\u00f3 en 1968 bajo la administraci\u00f3n del presidente Lyndon Johnson como la Semana de la Herencia Hispana. A\u00f1os m\u00e1s tarde, el presidente Ronald Reagan propuso extender la conmemoraci\u00f3n a un mes.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Se convirti\u00f3 en ley el 17 de agosto de 1988, y se design\u00f3 oficialmente al periodo de 30 d\u00edas entre el 15 de septiembre y el 15 de octubre como el Mes Nacional de la Herencia Hispana. Durante este per\u00edodo reconocemos la contribuci\u00f3n y logros de estadounidenses de origen hispano y latino que han beneficiado a nuestras comunidades y a la naci\u00f3n.&nbsp;Tambi\u00e9n celebramos la cultura y las tradiciones de los latinos e hispanos y sus logros en nuestra sociedad.&nbsp;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">La Fundaci\u00f3n Nacional Hispana para las Artes juega un papel importante en esta celebraci\u00f3n, como es de esperarse y su presidente F\u00e9lix S\u00e1nchez, afirma que &#8220;El Mes de la Herencia Hispana nos da la oportunidad de poner al d\u00eda al pueblo estadounidense sobre qui\u00e9nes son los latinos actualmente y de proporcionar un contexto contempor\u00e1neo a todas nuestras comunidades que son muy diferentes, que forman parte del ecosistema latino&#8221;.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Parte de ese contexto contempor\u00e1neo es el hecho de que los hispanos y los latinos constituyen una parte cada vez mayor de la poblaci\u00f3n general de Estados Unidos. El&nbsp;censo estadounidense&nbsp;de 2020 mostr\u00f3 que los hispanos y los latinos constituye el segundo grupo multirracial de r\u00e1pido crecimiento (solo detr\u00e1s de los asi\u00e1ticos, seg\u00fan el Pew Research Center). Para el 2020, 62,1 millones de personas se identificaron como hispanos o latinos, que representan el 18% de la poblaci\u00f3n total estadounidense. Ese n\u00famero hab\u00eda crecido un 23% desde 2010. En comparaci\u00f3n, la poblaci\u00f3n estadounidense que no es de origen hispano o latino creci\u00f3 solo un 4,3%, seg\u00fan los datos del censo. Debido a este porcentaje y a su contribuci\u00f3n a la sociedad, es necesario contar con la adecuada representaci\u00f3n ya que constituyen una gran parte de la poblaci\u00f3n del pa\u00eds.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>C\u00f3mo se celebra<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">En general, muchas ciudades del pa\u00eds realizan eventos que incluyen desfiles, celebran con fiestas y comparten platillos t\u00edpicos de pa\u00edses latinos, m\u00fasica, danzas folkl\u00f3ricas, visitan museos locales para saber m\u00e1s sobre la historia latina, se hacen donativos a organizaciones ben\u00e9ficas hispanas, o simplemente conocer y hablar con la comunidad que est\u00e1 a su alrededor. Saber qui\u00e9nes son y por qu\u00e9 est\u00e1n en los barrios en los que est\u00e1n, nos permite descubrir que probablemente tenemos m\u00e1s cosas en com\u00fan de las que pensamos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">En las escuelas p\u00fablicas y privadas hacen lecciones, reconociendo y honrando a los hispanos y latinos influyentes que han tenido un impacto en la sociedad estadounidense a trav\u00e9s de sus contribuciones a lo largo de los a\u00f1os.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Es importante tener en cuenta, seg\u00fan los expertos, que se puede reconocer y agradecer esa herencia en todo momento del a\u00f1o, fuera del periodo del \u201cMes de la Herencia Hispana\u201d ya que este, \u00fanicamente tiene la funci\u00f3n de ser un &#8220;mes de introducci\u00f3n&#8221; o un &#8220;punto de partida&#8221;, destac\u00f3 La directora de educaci\u00f3n del Centro Latino del Smithsonian, Emily Key.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">F\u00e9lix S\u00e1nchez sostiene que el &#8220;El Mes de la Herencia Hispana es una oportunidad para que la comunidad latina refuerce sus logros, pero tambi\u00e9n para que se extienda m\u00e1s all\u00e1 de la comunidad latina, para recordarles que todos somos estadounidenses&#8221;.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>\u00a1Feliz Mes de la Herencia Hispana!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Referencias:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/cnnespanol.cnn.com\/2021\/09\/15\/mes-herencia-hispana-comienza-mediados-septiembre-trax\/\">https:\/\/cnnespanol.cnn.com\/2021\/09\/15\/mes-herencia-hispana-comienza-mediados-septiembre-trax\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.telemundonuevainglaterra.com\/especiales\/mes-de-la-herencia-hispana\/cinco-cosas-que-debes-saber-sobre-el-mes-de-la-herencia-hispana\/2068412\/\">https:\/\/www.telemundonuevainglaterra.com\/especiales\/mes-de-la-herencia-hispana\/cinco-cosas-que-debes-saber-sobre-el-mes-de-la-herencia-hispana\/2068412\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por un mes, desde el&nbsp;15 de septiembre hasta el 15 de octubre, en Estados Unidos y en el mundo celebramos el Mes de la Herencia Hispana o tambi\u00e9n llamada Herencia Latina.&nbsp;La celebraci\u00f3n comienza a mediados de mes, como un gui\u00f1o a los aniversarios de la independencia nacional de varios pa\u00edses latinoamericanos: Costa Rica, El Salvador, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9,5],"tags":[],"class_list":["post-13053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-media-center"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrando el Mes de la Herencia Hispana - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrando el Mes de la Herencia Hispana - NHCOA\" \/>\n<meta property=\"og:description\" content=\"Por un mes, desde el&nbsp;15 de septiembre hasta el 15 de octubre, en Estados Unidos y en el mundo celebramos el Mes de la Herencia Hispana o tambi\u00e9n llamada Herencia Latina.&nbsp;La celebraci\u00f3n comienza a mediados de mes, como un gui\u00f1o a los aniversarios de la independencia nacional de varios pa\u00edses latinoamericanos: Costa Rica, El Salvador, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T14:18:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T14:19:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/09\/2-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Celebrando el Mes de la Herencia Hispana\",\"datePublished\":\"2022-09-28T14:18:30+00:00\",\"dateModified\":\"2022-09-28T14:19:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/\"},\"wordCount\":829,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2-3.png\",\"articleSection\":[\"Blog\",\"Media Center\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/\",\"name\":\"Celebrando el Mes de la Herencia Hispana - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2-3.png\",\"datePublished\":\"2022-09-28T14:18:30+00:00\",\"dateModified\":\"2022-09-28T14:19:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/celebrando-el-mes-de-la-herencia-hispana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrando el Mes de la Herencia Hispana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrando el Mes de la Herencia Hispana - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/","og_locale":"en_US","og_type":"article","og_title":"Celebrando el Mes de la Herencia Hispana - NHCOA","og_description":"Por un mes, desde el&nbsp;15 de septiembre hasta el 15 de octubre, en Estados Unidos y en el mundo celebramos el Mes de la Herencia Hispana o tambi\u00e9n llamada Herencia Latina.&nbsp;La celebraci\u00f3n comienza a mediados de mes, como un gui\u00f1o a los aniversarios de la independencia nacional de varios pa\u00edses latinoamericanos: Costa Rica, El Salvador, [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/","og_site_name":"NHCOA","article_published_time":"2022-09-28T14:18:30+00:00","article_modified_time":"2022-09-28T14:19:30+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/09\/2-3.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Celebrando el Mes de la Herencia Hispana","datePublished":"2022-09-28T14:18:30+00:00","dateModified":"2022-09-28T14:19:30+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/"},"wordCount":829,"image":{"@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/09\/2-3.png","articleSection":["Blog","Media Center"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/","url":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/","name":"Celebrando el Mes de la Herencia Hispana - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/09\/2-3.png","datePublished":"2022-09-28T14:18:30+00:00","dateModified":"2022-09-28T14:19:30+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/celebrando-el-mes-de-la-herencia-hispana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Celebrando el Mes de la Herencia Hispana"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13053"}],"version-history":[{"count":2,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13053\/revisions"}],"predecessor-version":[{"id":13055,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13053\/revisions\/13055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13049"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}