{"id":13222,"date":"2022-12-15T18:09:34","date_gmt":"2022-12-15T18:09:34","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13222"},"modified":"2022-12-15T18:09:37","modified_gmt":"2022-12-15T18:09:37","slug":"como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/","title":{"rendered":"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi?"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-1024x683.png\" alt=\"\" class=\"wp-image-13223\" width=\"512\" height=\"342\" srcset=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-1024x683.png 1024w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-300x200.png 300w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-768x512.png 768w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-1536x1024.png 1536w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-2048x1365.png 2048w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-1080x720.png 1080w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Desde que el desarrollo la vacuna contra la influenza, esta ha tenido una gran evoluci\u00f3n de acuerdo a las necesidades que los seres humanos crean. Muchos tienen dudas de cu\u00e1l vacuna es mejor o m\u00e1s conveniente para ellos y sus seres queridos. Es a partir de las investigaciones m\u00e9dicas que se definen las diferencias de cada uno de los tipos de vacunas existentes y su conveniencia. Las diferencias radican de acuerdo al paciente y las variantes del virus de la influenza que se encuentren en el ambiente. Dichas variantes cambian cada a\u00f1o a causa de diferentes factores medioambientales y de las poblaciones o seg\u00fan el hemisferio en el que nos encontremos.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-black-color has-text-color is-layout-flow wp-block-quote-is-layout-flow\" style=\"font-size:15px\"><p><strong>Seg\u00fan un estudio de los CDC del 2018 que se public\u00f3 en Clinical Infectious Diseases, el porcentaje de la poblaci\u00f3n de los Estados Unidos que se enferm\u00f3 de influenza es de aproximadamente el 8 por ciento, con un rango de entre el 3 y el 11 por ciento, seg\u00fan la temporada.<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Para saber cu\u00e1l vacuna es mejor para nosotros es necesario tomar en cuenta diferentes factores. Entre ellos, la edad y si tienen tendencia o historial al\u00e9rgico a las vacunas hechas con huevos.&nbsp; Hay muchas opciones de vacunas contra la influenza entre las que elegir, pero lo m\u00e1s importante es que todas las personas a partir de los 6 meses de edad se vacunen contra la influenza cada a\u00f1o. Tradicionalmente, las vacunas contra la gripe se han elaborado a partir de virus cultivados en huevos de gallina, aunque en los \u00faltimos a\u00f1os se han desarrollado vacunas sin huevo.&nbsp;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Conoce los diferentes tipos de vacunas disponibles en Estados Unidos, a continuaci\u00f3n:&nbsp;<\/p>\n\n\n\n<ul class=\"has-black-color has-text-color wp-block-list\" style=\"font-size:15px\"><li><strong>Vacuna contra la influenza de dosis est\u00e1ndar,<\/strong> que se elabora con virus de la influenza que se inactivan o eliminan. Muchas vacunas contra la gripe de dosis est\u00e1ndar que usan virus cultivados en huevos est\u00e1n aprobadas para su uso en personas de 6 meses de edad y mayores y, por lo general, se administran a trav\u00e9s de una inyecci\u00f3n con aguja en el m\u00fasculo del brazo.<\/li><li><strong>Vacuna contra la gripe a base de c\u00e9lulas,<\/strong> una vacuna inyectable sin huevo que se elabora a trav\u00e9s del cultivo de virus en cultivos de c\u00e9lulas de mam\u00edferos. Este tipo de vacuna tambi\u00e9n se puede administrar a personas a partir de los 6 meses de edad.<\/li><li><strong>Vacuna recombinante contra la gripe<\/strong>, una vacuna inyectable sin huevo que se fabrica sint\u00e9ticamente. Las vacunas recombinantes contra la gripe se pueden usar en personas mayores de 18 a\u00f1os.<\/li><li><strong>Vacuna antigripal con adyuvante<\/strong>, que incluye un ingrediente adicional (un adyuvante) dise\u00f1ado para aumentar, ampliar y prolongar la respuesta inmunitaria a la vacuna. Las vacunas contra la gripe con adyuvante son inyectables y est\u00e1n aprobadas para su uso en personas mayores de 65 a\u00f1os.<\/li><li><strong>Vacuna contra la gripe de dosis alta,<\/strong> que presenta una mayor cantidad de ant\u00edgeno que las vacunas contra la gripe de dosis est\u00e1ndar; en este contexto, los ant\u00edgenos son la parte de la vacuna que ayuda al organismo a generar una respuesta inmunitaria. Al igual que las vacunas contra la influenza con adyuvante, las vacunas contra la influenza en dosis altas son inyectables y est\u00e1n espec\u00edficamente aprobadas para su uso en personas de 65 a\u00f1os o m\u00e1s.<\/li><li><strong>Vacuna viva atenuada contra la influenza<\/strong>, que contiene un virus debilitado de la influenza y se administra a trav\u00e9s de un aerosol nasal. Las personas que tienen entre 2 y 49 a\u00f1os pueden recibir esta vacuna, pero algunas (por ejemplo, las embarazadas o inmunocomprometidas) no deber\u00edan recibirla.<\/li><\/ul>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">La vacunaci\u00f3n para prevenir la influenza y sus posibles complicaciones graves es especialmente importante para las personas con mayor riesgo de presentar complicaciones por la influenza. Adem\u00e1s, la vacunaci\u00f3n previene contraer dicha enfermedad en temporada de gripe. Aqu\u00ed radica la importancia de la vacunaci\u00f3n: protegernos a nosotros mismos y a nuestros seres queridos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Si tiene preguntas sobre qu\u00e9 vacuna es mejor para usted, consulte con su m\u00e9dico u otro profesional de la salud. Hay m\u00e1s informaci\u00f3n disponible sobre las vacunas contra la influenza aprobadas para la temporada de influenza 2021-2022 y las indicaciones acordes a la edad para cada vacuna. Para m\u00e1s informaci\u00f3n puede visitar el sitio:<a href=\"https:\/\/espanol.cdc.gov\/flu\"> espanol.cdc.gov\/flu<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Referencias:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/espanol.cdc.gov\/flu\/about\/keyfacts.htm\">https:\/\/espanol.cdc.gov\/flu\/about\/keyfacts.htm<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/espanol.cdc.gov\/flu\/prevent\/flushot.htm\">https:\/\/espanol.cdc.gov\/flu\/prevent\/flushot.htm<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/theconversation.com\/por-que-existen-diferentes-vacunas-contra-la-gripe-151703\">https:\/\/theconversation.com\/por-que-existen-diferentes-vacunas-contra-la-gripe-151703<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.flu.com\/Articles\/2022\/Overview-of-Flu-Vaccine-Types\">https:\/\/www.flu.com\/Articles\/2022\/Overview-of-Flu-Vaccine-Types<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que el desarrollo la vacuna contra la influenza, esta ha tenido una gran evoluci\u00f3n de acuerdo a las necesidades que los seres humanos crean. Muchos tienen dudas de cu\u00e1l vacuna es mejor o m\u00e1s conveniente para ellos y sus seres queridos. Es a partir de las investigaciones m\u00e9dicas que se definen las diferencias de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9,5],"tags":[56,57,45,55],"class_list":["post-13222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-media-center","tag-dosis","tag-gripe","tag-influenza","tag-vacuna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi? - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi? - NHCOA\" \/>\n<meta property=\"og:description\" content=\"Desde que el desarrollo la vacuna contra la influenza, esta ha tenido una gran evoluci\u00f3n de acuerdo a las necesidades que los seres humanos crean. Muchos tienen dudas de cu\u00e1l vacuna es mejor o m\u00e1s conveniente para ellos y sus seres queridos. Es a partir de las investigaciones m\u00e9dicas que se definen las diferencias de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T18:09:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T18:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi?\",\"datePublished\":\"2022-12-15T18:09:34+00:00\",\"dateModified\":\"2022-12-15T18:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/\"},\"wordCount\":770,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Flu-vaccine-blog-1.png\",\"keywords\":[\"dosis\",\"gripe\",\"Influenza\",\"vacuna\"],\"articleSection\":[\"Blog\",\"Media Center\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/\",\"name\":\"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi? - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Flu-vaccine-blog-1.png\",\"datePublished\":\"2022-12-15T18:09:34+00:00\",\"dateModified\":\"2022-12-15T18:09:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi? - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi? - NHCOA","og_description":"Desde que el desarrollo la vacuna contra la influenza, esta ha tenido una gran evoluci\u00f3n de acuerdo a las necesidades que los seres humanos crean. Muchos tienen dudas de cu\u00e1l vacuna es mejor o m\u00e1s conveniente para ellos y sus seres queridos. Es a partir de las investigaciones m\u00e9dicas que se definen las diferencias de [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/","og_site_name":"NHCOA","article_published_time":"2022-12-15T18:09:34+00:00","article_modified_time":"2022-12-15T18:09:37+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1-1024x683.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi?","datePublished":"2022-12-15T18:09:34+00:00","dateModified":"2022-12-15T18:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/"},"wordCount":770,"image":{"@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1.png","keywords":["dosis","gripe","Influenza","vacuna"],"articleSection":["Blog","Media Center"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/","url":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/","name":"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi? - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2022\/12\/Flu-vaccine-blog-1.png","datePublished":"2022-12-15T18:09:34+00:00","dateModified":"2022-12-15T18:09:37+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/como-elijo-la-mejor-vacuna-contra-la-influenza-para-mi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo elijo\u00a0la mejor vacuna contra la influenza para mi?"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13222"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13222\/revisions"}],"predecessor-version":[{"id":13224,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13222\/revisions\/13224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13223"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}