{"id":13401,"date":"2023-05-12T14:56:28","date_gmt":"2023-05-12T14:56:28","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13401"},"modified":"2023-05-12T14:56:30","modified_gmt":"2023-05-12T14:56:30","slug":"evita-la-desnutricion-en-adultos-mayores","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/","title":{"rendered":"Evita la desnutrici\u00f3n en adultos mayores"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/05\/Blog-header-5-Post-de-Twitter-13-1024x576.png\" alt=\"\" class=\"wp-image-13402\" width=\"512\" height=\"288\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Nos referimos a <strong>desnutrici\u00f3n cuando una persona tiene una dieta que no es adecuada para su organismo. <\/strong>Esta dieta no le permite obtener los nutrientes necesarios para que su cuerpo y sus \u00f3rganos tengan un buen funcionamiento. <strong>En los adultos mayores, la desnutrici\u00f3n se manifiesta en un mayor cansancio debido a la falta de vitaminas y minerales.<\/strong> El cuerpo busca mantener el ritmo de un organismo sano y ocupa las reservas de energ\u00eda para funcionar correctamente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Los adultos mayores necesitan de distintos requerimientos nutricionales, debido a los cambios en esta etapa de la vida. El funcionamiento de muchos sistemas del cuerpo comienzan a cambiar y, por lo tanto, las necesidades nutricionales cambian con ellas. Es importante prestar atenci\u00f3n a estas modificaciones y a su vez, tener en cuenta las limitaciones por enfermedades subyacentes o aquellas que pueden complicar el estado nutricional de un adulto mayor.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">El Servicio Nacional del Consumidor del Gobierno de Chile indica que existen elementos relacionados con el envejecimiento que est\u00e1n asociadas directamente con la desnutrici\u00f3n. Entre ellos se destaca un mayor descontrol en los estados emocionales, que muchas veces los motiva a no comer, como una forma de protestar o de llamar la atenci\u00f3n. Se\u00f1ala tambi\u00e9n la ingesta exagerada, producto de estados ansiosos o de soledad, que de igual forma pueden derivar en una mala nutrici\u00f3n.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Respecto a consecuencias f\u00edsicas, menciona la <strong>disminuci\u00f3n en la sensaci\u00f3n del gusto y del olfato<\/strong>. Las papilas gustativas que m\u00e1s se afectan son las de la parte anterior de la lengua, las que diferencian gustos dulces y salados. Esto puede llevar a reducir el deseo de comer y es aqu\u00ed donde se debe prestar m\u00e1s atenci\u00f3n para poder brindarles opciones sanas para compensar esas limitaciones.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Por otra parte, los adultos mayores presentan <strong>menor acidez g\u00e1strica<\/strong>, un <strong>retardo en el vaciamiento intestinal<\/strong> y una <strong>movilidad intestinal disminuida<\/strong>. Lo anterior tambi\u00e9n puede padecer interferencias propias causadas por la ingesta de diversos medicamentos a la vez.<br>Adem\u00e1s, la boca, el lugar en el que inicia la nutrici\u00f3n, sufre m\u00faltiples modificaciones. En ella pueden presentarse la <strong>p\u00e9rdida progresiva de piezas dentales<\/strong> y con esto, la <strong>incomodidad del uso de pr\u00f3tesis dentales<\/strong>. Dichas barreras generan otras molestias al momento de ingerir los alimentos, como verg\u00fcenza al comer frente a otras personas, adopci\u00f3n de una dieta m\u00e1s blanda y diferentes sabores que compensen necesidades nutricionales.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Para saber si podemos enfrentarnos a la desnutrici\u00f3n en adultos mayores, debemos prestar atenci\u00f3n a los siguientes s\u00edntoma<\/strong>s. Recuerda, es necesario contar siempre con un seguimiento m\u00e9dico que pueda monitorear y verificar la salud peri\u00f3dicamente de la persona.<\/p>\n\n\n\n<ul class=\"has-black-color has-text-color wp-block-list\" style=\"font-size:15px\">\n<li>P\u00e9rdida de peso no intencionada en grandes porcentajes durante los \u00faltimos meses.<\/li>\n\n\n\n<li>Disminuci\u00f3n de la masa muscular que se puede apreciar en los brazos o las pantorrillas.<\/li>\n\n\n\n<li>P\u00e9rdida del apetito.<\/li>\n\n\n\n<li>P\u00e9rdida de fuerza en los m\u00fasculos. Se puede detectar al intentar tomar un objeto o levantar algo de peso.<\/li>\n\n\n\n<li>Tos y atragantamientos constantes al comer o beber.<\/li>\n\n\n\n<li>Mayor cansancio al levantarse, caminar o al hacer cualquier otro tipo de actividad f\u00edsica.<\/li>\n\n\n\n<li>Fatiga.<\/li>\n\n\n\n<li>V\u00e9rtigos.<\/li>\n\n\n\n<li>Irritabilidad.<\/li>\n\n\n\n<li>Depresi\u00f3n.<\/li>\n\n\n\n<li>Diarrea o estre\u00f1imiento.<\/li>\n\n\n\n<li>Resequedad en la piel y el cabello.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Tal como se mencion\u00f3 anteriormente, <strong>el organismo del adulto mayor comienza a exigir la ingesta de ciertos nutrientes que le permitan cubrir todas las necesidades nutricionales que son vitales para mantener una vida saludable.<\/strong> Es por esto que el cambio de h\u00e1bitos alimenticios y de una dieta apta para las necesidades nutricionales ser\u00e1 la mejor herramienta para defender de la desnutrici\u00f3n a nuestros adultos mayores. Se debe incluir en la dieta: frutas, vegetales, carnes magras y granos integrales y reducir el consumo de grasas s\u00f3lidas, sal y az\u00facares.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Es fundamental una dieta equilibrada, alimentarse con comidas que estimulan su apetito y sean f\u00e1ciles de masticar y digerir.<\/strong> Esto les permitir\u00e1 conservar una buena salud, incluso mejorarla gradualmente para el resto de sus vidas. <strong>Asimismo, el ejercicio f\u00edsico mantendr\u00e1 fuertes sus huesos y m\u00fasculos, mejorando incluso el apetito. <\/strong>Todas estas recomendaciones evitar\u00e1n la malnutrici\u00f3n en los adultos mayores y asegurar\u00e1 la selecci\u00f3n de alimentos saludables.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Referencias:<br><\/strong><a href=\"Referencias: Desnutrici\u00f3n en el adulto mayor | Aprende Institute Nutrici\u00f3n en el Adulto Mayor \u25b7 Gu\u00eda Completa 2023 (canitas.mx) (Microsoft Word - Nutricion y Cuidados del Adulto Mayor. Estudio Monografico\\205) (fiapam.org)\">Desnutrici\u00f3n en el adulto mayor | Aprende Institute<br>Nutrici\u00f3n en el Adulto Mayor \u25b7 Gu\u00eda Completa 2023 (canitas.mx)<br>(Microsoft Word &#8211; Nutricion y Cuidados del Adulto Mayor. Estudio Monografico\\205) (fiapam.org)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos referimos a desnutrici\u00f3n cuando una persona tiene una dieta que no es adecuada para su organismo. Esta dieta no le permite obtener los nutrientes necesarios para que su cuerpo y sus \u00f3rganos tengan un buen funcionamiento. En los adultos mayores, la desnutrici\u00f3n se manifiesta en un mayor cansancio debido a la falta de vitaminas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9,5],"tags":[],"class_list":["post-13401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-media-center"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evita la desnutrici\u00f3n en adultos mayores - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evita la desnutrici\u00f3n en adultos mayores - NHCOA\" \/>\n<meta property=\"og:description\" content=\"Nos referimos a desnutrici\u00f3n cuando una persona tiene una dieta que no es adecuada para su organismo. Esta dieta no le permite obtener los nutrientes necesarios para que su cuerpo y sus \u00f3rganos tengan un buen funcionamiento. En los adultos mayores, la desnutrici\u00f3n se manifiesta en un mayor cansancio debido a la falta de vitaminas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-12T14:56:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-12T14:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/05\/Blog-header-5-Post-de-Twitter-13.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Evita la desnutrici\u00f3n en adultos mayores\",\"datePublished\":\"2023-05-12T14:56:28+00:00\",\"dateModified\":\"2023-05-12T14:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/\"},\"wordCount\":755,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Blog-header-5-Post-de-Twitter-13.png\",\"articleSection\":[\"Blog\",\"Media Center\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/\",\"name\":\"Evita la desnutrici\u00f3n en adultos mayores - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Blog-header-5-Post-de-Twitter-13.png\",\"datePublished\":\"2023-05-12T14:56:28+00:00\",\"dateModified\":\"2023-05-12T14:56:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/evita-la-desnutricion-en-adultos-mayores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evita la desnutrici\u00f3n en adultos mayores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evita la desnutrici\u00f3n en adultos mayores - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/","og_locale":"en_US","og_type":"article","og_title":"Evita la desnutrici\u00f3n en adultos mayores - NHCOA","og_description":"Nos referimos a desnutrici\u00f3n cuando una persona tiene una dieta que no es adecuada para su organismo. Esta dieta no le permite obtener los nutrientes necesarios para que su cuerpo y sus \u00f3rganos tengan un buen funcionamiento. En los adultos mayores, la desnutrici\u00f3n se manifiesta en un mayor cansancio debido a la falta de vitaminas [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/","og_site_name":"NHCOA","article_published_time":"2023-05-12T14:56:28+00:00","article_modified_time":"2023-05-12T14:56:30+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/05\/Blog-header-5-Post-de-Twitter-13.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Evita la desnutrici\u00f3n en adultos mayores","datePublished":"2023-05-12T14:56:28+00:00","dateModified":"2023-05-12T14:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/"},"wordCount":755,"image":{"@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/05\/Blog-header-5-Post-de-Twitter-13.png","articleSection":["Blog","Media Center"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/","url":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/","name":"Evita la desnutrici\u00f3n en adultos mayores - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/05\/Blog-header-5-Post-de-Twitter-13.png","datePublished":"2023-05-12T14:56:28+00:00","dateModified":"2023-05-12T14:56:30+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/evita-la-desnutricion-en-adultos-mayores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Evita la desnutrici\u00f3n en adultos mayores"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13401"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13401\/revisions"}],"predecessor-version":[{"id":13403,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13401\/revisions\/13403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13402"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}