{"id":13548,"date":"2023-07-13T17:42:00","date_gmt":"2023-07-13T17:42:00","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13548"},"modified":"2023-07-13T17:42:01","modified_gmt":"2023-07-13T17:42:01","slug":"la-importancia-del-ejercicio-para-el-adulto-mayor","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/","title":{"rendered":"La importancia del ejercicio para el adulto mayor"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/07\/Blog-header-10-1024x576.png\" alt=\"\" class=\"wp-image-13549\" width=\"512\" height=\"288\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Ya hemos hablado anteriormente sobre la alimentaci\u00f3n adecuada para adultos mayores. Sabemos que una buena alimentaci\u00f3n es la base para una vida saludable pero tambi\u00e9n es importante <strong>tener una buena rutina de ejercicios que complemente las buenas pr\u00e1cticas alimenticias.\u00a0Hacer actividad f\u00edsica regularmente te ayuda a prevenir o retrasar muchos problemas de salud que surgen con el tiempo.<\/strong> Asimismo, ayuda a fortalecer los m\u00fasculos para que pueda hacer sus tareas diarias sin tener que depender de otros.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Es importante tomar en cuenta que algunas condiciones cr\u00f3nicas pueden afectar la capacidad del adulto mayor para cumplir con estas recomendaciones. Los adultos mayores deben ser tan activos f\u00edsicamente como lo permitan sus habilidades y condiciones.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">El Centro para el Control y Prevenci\u00f3n de las Enfermedades (CDC, por sus siglas en ingl\u00e9s) recomienda en su publicaci\u00f3n de la segunda edici\u00f3n de las<strong><em> Pautas de Actividad F\u00edsica para Estadounidenses (Physical Activity Guidelines for Americans, en ingl\u00e9s) <\/em><\/strong>una serie de actividades f\u00edsicas seg\u00fan la edad. En el caso de los adultos mayores propone lo siguiente:<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">\u25cf Al menos <strong>150 minutos<\/strong> a la semana de actividad de intensidad moderada, como caminar a paso ligero.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">\u25cf Al menos<strong> 2 d\u00edas a la semana<\/strong> de actividades que fortalezcan los m\u00fasculos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">\u25cf Actividades para<strong> mejorar el equilibrio<\/strong> como pararse en un pie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">En el caso de adultos mayores con condiciones cr\u00f3nicas o discapacidades, sugiere actividad f\u00edsica con menor intensidad:&nbsp;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">\u25cf Realizar al menos\u00a0<strong>150 minutos\u00a0(por ejemplo, 30 minutos 5 d\u00edas a la semana)<\/strong>\u00a0de actividad f\u00edsica aer\u00f3bica de intensidad moderada a la semana.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">\u25cf Realizar al menos\u00a02 d\u00edas a la semana actividades de <strong>fortalecimiento muscular<\/strong>\u00a0que incluyan todos los grupos musculares principales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Unos de los cambios m\u00e1s comunes en las personas mayores son los que <strong>ocurren a nivel de la masa muscular, grasa y agua corporal, los cu\u00e1les son los que menos se perciben<\/strong>. Sin embargo, son los m\u00e1s importantes para determinar el nivel de dependencia en los adultos mayores. <\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">En el caso de la masa muscular en los adultos mayores, la p\u00e9rdida puede llegar a ser de hasta el 40%. Respecto a la grasa, hay un aumento proporcional a la disminuci\u00f3n de la masa muscular. Finalmente, el agua corporal en una persona a lo largo de su vida llega al 70%, a partir de los 65 a\u00f1os puede disminuir hasta el 50%.\u00a0<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Lo anterior puede recular en una mayor dificultad para desempe\u00f1ar funciones motoras, una mayor facilidad de deshidratarse y una menor resistencia al ejercicio. Debido a estos cambios surgen problemas en el mantenimiento de la temperatura corporal y una alteraci\u00f3n en el metabolismo de los adultos mayores.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Los adultos mayores deben incluir en su rutina diaria la actividad f\u00edsica seg\u00fan sus posibilidades. La pr\u00e1ctica continua de ejercicio mejorar\u00e1 la funcionalidad e independencia, asimismo ser\u00e1 beneficioso para su estado de \u00e1nimo y calidad de vida. Su familia, cuidadores y amigos tendr\u00e1n un papel primordial en esta rutina para poder conservarla en el tiempo.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">La actividad f\u00edsica regular es una de las cosas m\u00e1s importantes que las personas pueden hacer para mejorar su salud, en general.\u00a0<strong>Moverse m\u00e1s y sentarse menos tiene enormes beneficios para todos, independientemente de la edad, el sexo, la raza, el origen \u00e9tnico o el estado f\u00edsico actual.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>References:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cdc.gov\/physicalactivity\/basics\/age-chart.html\">https:\/\/www.cdc.gov\/physicalactivity\/basics\/age-chart.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cdc.gov\/physicalactivity\/basics\/spanish\/cuanta-actividad-fisica-necesitan-los-adultos-mayores.htm\">https:\/\/www.cdc.gov\/physicalactivity\/basics\/spanish\/cuanta-actividad-fisica-necesitan-los-adultos-mayores.htm<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.salud.mapfre.es\/salud-familiar\/mayores\/cambios-en-la-vejez\/cambios-en-la-composicion-corporal\/\">https:\/\/www.salud.mapfre.es\/salud-familiar\/mayores\/cambios-en-la-vejez\/cambios-en-la-composicion-corporal\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.scielo.org.mx\/scielo.php?script=sci_arttext&amp;pid=S0016-38132004000400013\">https:\/\/www.scielo.org.mx\/scielo.php?script=sci_arttext&amp;pid=S0016-38132004000400013<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya hemos hablado anteriormente sobre la alimentaci\u00f3n adecuada para adultos mayores. Sabemos que una buena alimentaci\u00f3n es la base para una vida saludable pero tambi\u00e9n es importante tener una buena rutina de ejercicios que complemente las buenas pr\u00e1cticas alimenticias.\u00a0Hacer actividad f\u00edsica regularmente te ayuda a prevenir o retrasar muchos problemas de salud que surgen con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9,5],"tags":[],"class_list":["post-13548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-media-center"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La importancia del ejercicio para el adulto mayor - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La importancia del ejercicio para el adulto mayor - NHCOA\" \/>\n<meta property=\"og:description\" content=\"Ya hemos hablado anteriormente sobre la alimentaci\u00f3n adecuada para adultos mayores. Sabemos que una buena alimentaci\u00f3n es la base para una vida saludable pero tambi\u00e9n es importante tener una buena rutina de ejercicios que complemente las buenas pr\u00e1cticas alimenticias.\u00a0Hacer actividad f\u00edsica regularmente te ayuda a prevenir o retrasar muchos problemas de salud que surgen con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-13T17:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-13T17:42:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/07\/Blog-header-10.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"La importancia del ejercicio para el adulto mayor\",\"datePublished\":\"2023-07-13T17:42:00+00:00\",\"dateModified\":\"2023-07-13T17:42:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/\"},\"wordCount\":610,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Blog-header-10.png\",\"articleSection\":[\"Blog\",\"Media Center\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/\",\"name\":\"La importancia del ejercicio para el adulto mayor - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Blog-header-10.png\",\"datePublished\":\"2023-07-13T17:42:00+00:00\",\"dateModified\":\"2023-07-13T17:42:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/la-importancia-del-ejercicio-para-el-adulto-mayor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La importancia del ejercicio para el adulto mayor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La importancia del ejercicio para el adulto mayor - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/","og_locale":"en_US","og_type":"article","og_title":"La importancia del ejercicio para el adulto mayor - NHCOA","og_description":"Ya hemos hablado anteriormente sobre la alimentaci\u00f3n adecuada para adultos mayores. Sabemos que una buena alimentaci\u00f3n es la base para una vida saludable pero tambi\u00e9n es importante tener una buena rutina de ejercicios que complemente las buenas pr\u00e1cticas alimenticias.\u00a0Hacer actividad f\u00edsica regularmente te ayuda a prevenir o retrasar muchos problemas de salud que surgen con [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/","og_site_name":"NHCOA","article_published_time":"2023-07-13T17:42:00+00:00","article_modified_time":"2023-07-13T17:42:01+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/07\/Blog-header-10.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"La importancia del ejercicio para el adulto mayor","datePublished":"2023-07-13T17:42:00+00:00","dateModified":"2023-07-13T17:42:01+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/"},"wordCount":610,"image":{"@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/07\/Blog-header-10.png","articleSection":["Blog","Media Center"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/","url":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/","name":"La importancia del ejercicio para el adulto mayor - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/07\/Blog-header-10.png","datePublished":"2023-07-13T17:42:00+00:00","dateModified":"2023-07-13T17:42:01+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/la-importancia-del-ejercicio-para-el-adulto-mayor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"La importancia del ejercicio para el adulto mayor"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13548"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13548\/revisions"}],"predecessor-version":[{"id":13550,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13548\/revisions\/13550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13549"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}