{"id":13595,"date":"2023-08-16T14:45:12","date_gmt":"2023-08-16T14:45:12","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13595"},"modified":"2023-08-16T14:45:14","modified_gmt":"2023-08-16T14:45:14","slug":"afecciones-persistentes-al-covid-19","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/","title":{"rendered":"Afecciones persistentes al COVID-19"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16.png\" alt=\"\" class=\"wp-image-13589\" style=\"width:641px\" width=\"641\" srcset=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16.png 1600w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16-1280x720.png 1280w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16-980x551.png 980w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1600px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Si bien es cierto el COVID-19 ya no supone una amenaza a la salud p\u00fablica, es importante tomar en cuenta que el virus sigue entre nosotros. <strong>Seg\u00fan investigaciones de los CDC, algunas personas que se infectaron por el virus que causa el COVID-19 pueden tener efectos a largo plazo por la infecci\u00f3n, conocidos como afecciones persistentes al COVID-19 o afecciones posteriores al COVID-19 (PCC, por sus siglas en ingl\u00e9s).<\/strong> A pesar que todas las personas que se infectaron con el virus son propensas a tener afecciones persistentes al COVID-19, es m\u00e1s frecuente que se desarrolle en <strong>aquellos pacientes que se enfermaron gravemente a causa del virus<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Las afecciones persistentes al COVID-19 son s\u00edntomas y afecciones que persisten o se desarrollan tras una infecci\u00f3n inicial por COVID-19. Esta definici\u00f3n de afecciones persistentes al COVID-19 fue elaborada por el Departamento de Salud y Servicios Humanos (HHS), junto con los CDC y otros socios.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Las afecciones persistentes al COVID-19 son una variedad de problemas de salud nuevos, reca\u00eddas o afecciones en curso que se experimentan despu\u00e9s de infectarse por el virus que causa el COVID-19. Es decir, <strong>son s\u00edntomas que se presentan semanas, meses y hasta a\u00f1os despu\u00e9s de haber contra\u00eddo el COVID-19. Se caracterizan porque son s\u00edntomas de la enfermedad que se agudizan con el tiempo y que persisten en el paciente, pese al tratamiento m\u00e9dico.<\/strong> La mayor\u00eda de las personas con COVID-19 mejora al cabo de unos d\u00edas o semanas, as\u00ed que las afecciones persistentes al COVID-19 aparecen al menos cuatro semanas despu\u00e9s de la infecci\u00f3n y reci\u00e9n pueden detectarse.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">No hay una prueba para determinar si los s\u00edntomas o afecci\u00f3n son consecuencia del COVID-19, por lo que <strong>un proveedor de atenci\u00f3n m\u00e9dica deber\u00e1 considerar el historial previo de infecci\u00f3n por COVID-19 para hacer el diagn\u00f3stico de afecciones persistentes al COVID-19.<\/strong> El historial previo de infecci\u00f3n incluye si le diagnosticaron COVID-19 mediante una prueba de detecci\u00f3n con resultado positivo o por los s\u00edntomas o exposici\u00f3n, as\u00ed como un examen de salud.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Una investigaci\u00f3n en Estados Unidos que ha sido financiada por los Institutos Nacionales de Salud (NIH) de los Estados Unidos y que forma parte del proyecto <strong><em>&#8216;Researching Covid to Enhance Recovery&#8217; <\/em><\/strong>del NIH, arroja 12 principales s\u00edntomas del COVID Persistente:<\/p>\n\n\n\n<ol class=\"has-black-color has-text-color wp-block-list\" style=\"font-size:15px\">\n<li>Malestar despu\u00e9s del esfuerzo<\/li>\n\n\n\n<li>Fatiga<\/li>\n\n\n\n<li>Confusi\u00f3n mental<\/li>\n\n\n\n<li>Mareos<\/li>\n\n\n\n<li>S\u00edntomas gastrointestinales<\/li>\n\n\n\n<li>Palpitaciones<\/li>\n\n\n\n<li>Disminuci\u00f3n del deseo o problemas sexuales<\/li>\n\n\n\n<li>P\u00e9rdida del olfato o del gusto<\/li>\n\n\n\n<li>Sed<\/li>\n\n\n\n<li>Tos cr\u00f3nica<\/li>\n\n\n\n<li>Dolor tor\u00e1cico<\/li>\n\n\n\n<li>Movilidad anormal<\/li>\n<\/ol>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Este proyecto se realiz\u00f3 con 10,000 pacientes en EE.UU. y se realiz\u00f3 con el objetivo de comprender por qu\u00e9 algunas personas desarrollan s\u00edntomas a largo plazo tras la infecci\u00f3n por COVID-19 y tambi\u00e9n para identificar, tratar y prevenir el COVID persistente.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\">Aunque los expertos se\u00f1alan estos 12 s\u00edntomas principales, las personas con afecciones persistentes al COVID-19 pueden tener problemas de salud con diferentes tipos y combinaciones de s\u00edntomas durante diferentes periodos y pueden o no ser parte de la lista que sugerimos anteriormente. <strong>Por lo que insistimos en hablar con su m\u00e9dico acerca de sus s\u00edntomas despu\u00e9s de tener COVID-19 para determinar si podr\u00eda tener afecciones persistentes al COVID-19 y el tratamiento adecuado para contrarrestar los s\u00edntomas.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\" style=\"font-size:15px\"><strong>Hay estudios que sugieren que las personas que contraen el COVID-19 despu\u00e9s de vacunarse tienen una tendencia m\u00e1s baja a desarrollar afecciones persistentes al COVID-19 que las personas que no est\u00e1n vacunadas.<\/strong> De igual forma, sugieren que las personas que no est\u00e1n vacunadas contra el COVID-19 y contraen el virus, corren mayor riesgo de tener afecciones persistentes al COVID-19 que las personas vacunadas. Es por esto que la mejor forma de prevenir las afecciones persistentes al COVID-19 es tener al d\u00eda el esquema de vacunaci\u00f3n y sus dosis de refuerzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>Referencias:<br><\/strong><a href=\"https:\/\/espanol.cdc.gov\/coronavirus\/2019-ncov\/long-term-effects\/index.html\">https:\/\/espanol.cdc.gov\/coronavirus\/2019-ncov\/long-term-effects\/index.html<br><\/a><a href=\"https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2023\/06\/01\/64787d3321efa01e168b45bf.html\">https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2023\/06\/01\/64787d3321efa01e168b45bf.html<br><\/a><a href=\"https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2022\/08\/05\/62ebe6ddfc6c8378758b45e8.html\">https:\/\/www.elmundo.es\/ciencia-y-salud\/salud\/2022\/08\/05\/62ebe6ddfc6c8378758b45e8.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien es cierto el COVID-19 ya no supone una amenaza a la salud p\u00fablica, es importante tomar en cuenta que el virus sigue entre nosotros. Seg\u00fan investigaciones de los CDC, algunas personas que se infectaron por el virus que causa el COVID-19 pueden tener efectos a largo plazo por la infecci\u00f3n, conocidos como afecciones [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9],"tags":[59,58,19,140],"class_list":["post-13595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-coronavirus","tag-covid","tag-covid-19","tag-pandemia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afecciones persistentes al COVID-19 - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afecciones persistentes al COVID-19 - NHCOA\" \/>\n<meta property=\"og:description\" content=\"Si bien es cierto el COVID-19 ya no supone una amenaza a la salud p\u00fablica, es importante tomar en cuenta que el virus sigue entre nosotros. Seg\u00fan investigaciones de los CDC, algunas personas que se infectaron por el virus que causa el COVID-19 pueden tener efectos a largo plazo por la infecci\u00f3n, conocidos como afecciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-16T14:45:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T14:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Afecciones persistentes al COVID-19\",\"datePublished\":\"2023-08-16T14:45:12+00:00\",\"dateModified\":\"2023-08-16T14:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/\"},\"wordCount\":700,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Blog-header-16.png\",\"keywords\":[\"coronavirus\",\"covid\",\"covid-19\",\"pandemia\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/\",\"name\":\"Afecciones persistentes al COVID-19 - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Blog-header-16.png\",\"datePublished\":\"2023-08-16T14:45:12+00:00\",\"dateModified\":\"2023-08-16T14:45:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/afecciones-persistentes-al-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afecciones persistentes al COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afecciones persistentes al COVID-19 - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"Afecciones persistentes al COVID-19 - NHCOA","og_description":"Si bien es cierto el COVID-19 ya no supone una amenaza a la salud p\u00fablica, es importante tomar en cuenta que el virus sigue entre nosotros. Seg\u00fan investigaciones de los CDC, algunas personas que se infectaron por el virus que causa el COVID-19 pueden tener efectos a largo plazo por la infecci\u00f3n, conocidos como afecciones [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/","og_site_name":"NHCOA","article_published_time":"2023-08-16T14:45:12+00:00","article_modified_time":"2023-08-16T14:45:14+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Afecciones persistentes al COVID-19","datePublished":"2023-08-16T14:45:12+00:00","dateModified":"2023-08-16T14:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/"},"wordCount":700,"image":{"@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16.png","keywords":["coronavirus","covid","covid-19","pandemia"],"articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/","url":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/","name":"Afecciones persistentes al COVID-19 - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/08\/Blog-header-16.png","datePublished":"2023-08-16T14:45:12+00:00","dateModified":"2023-08-16T14:45:14+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/afecciones-persistentes-al-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Afecciones persistentes al COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13595"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13595\/revisions"}],"predecessor-version":[{"id":13596,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13595\/revisions\/13596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13589"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}