{"id":13747,"date":"2023-11-17T14:52:03","date_gmt":"2023-11-17T14:52:03","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13747"},"modified":"2023-11-17T14:52:05","modified_gmt":"2023-11-17T14:52:05","slug":"nuevos-tratamientos-antivirales-contra-el-covid-19","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/","title":{"rendered":"Nuevos tratamientos antivirales contra el COVID-19"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47-1024x576.png\" alt=\"\" class=\"wp-image-13745\" style=\"width:550px\" srcset=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47-980x551.png 980w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"font-size:15px\">A tres a\u00f1os de la pandemia del COVID-19 y a menos de un a\u00f1o de declarar el fin del virus como una emergencia de salud p\u00fablica de importancia internacional, no podemos dejar de considerar el virus como una amenaza para la salud mundial. El virus lleg\u00f3 para quedarse, y los pa\u00edses ahora deben <strong>integrar pr\u00e1cticas de vigilancia y respuesta al COVID-19 en sus programas de salud regulares<\/strong> que respondan a un mejor tratamiento de la enfermedad para la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\" style=\"font-size:15px\">Actualmente, la mayor\u00eda de las personas con COVID-19 pueden recuperarse en casa y pueden tratar los s\u00edntomas con medicamentos de venta libre, como paracetamol o ibuprofeno. Por otro lado, si tiene m\u00e1s probabilidades de enfermarse gravemente,<strong> hay tratamientos disponibles que pueden reducir sus posibilidades de ser hospitalizado o morir a causa de la enfermedad<\/strong>. En estos casos, los medicamentos para tratar el COVID-19 deben ser <strong>recetados por un proveedor de atenci\u00f3n m\u00e9dica<\/strong> o un farmac\u00e9utico y deben comenzar a administrarse entre 5 y 7 d\u00edas despu\u00e9s de la aparici\u00f3n de los s\u00edntomas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\" style=\"font-size:15px\"><strong>Es importante comunicarse con un proveedor de atenci\u00f3n m\u00e9dica de inmediato para determinar si es elegible para recibir tratamiento, incluso si sus s\u00edntomas actualmente son leves. Desafortunadamente, muchos de los que necesitan tratamientos contra el COVID-19 no saben que los tratamientos son una opci\u00f3n y no los reciben.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\" style=\"font-size:15px\">Tambi\u00e9n es posible que comunidades vulnerables no est\u00e9n recibiendo un acceso adecuado a los tratamientos contra el COVID-19, incluyendo los antivirales debido a la falta de acceso a la informaci\u00f3n adecuada. Es por eso que en este blog compartimos m\u00e1s sobre los nuevos tratamientos aprobados para el tratamiento del COVID-19 y sobre quienes son las comunidades de mayor riesgo al contraer la enfermedad.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\" style=\"font-size:15px\">En primera instancia, la edad es el mayor factor de riesgo, el cu\u00e1l tambi\u00e9n aumenta si el paciente padece de condiciones de salud como diabetes, c\u00e1ncer, problemas de salud mental, obesidad, asma u otros. Si una persona tiene s\u00edntomas de COVID-19 leves a moderados, puede ser elegible para <strong>una de las dos opciones de tratamiento antiviral disponibles para ayudar a prevenir el COVID-19 grave<\/strong>: antivirales orales y antivirales intravenosos (IV).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-size:15px\">Los<strong> antivirales orales<\/strong> son pastillas que se pueden tomar por v\u00eda oral y se pueden obtener en una farmacia. El tratamiento debe comenzar dentro de los primeros cinco d\u00edas.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-size:15px\">Los<strong> antivirales intravenosos<\/strong> deben administrarse en un hospital u otro centro de atenci\u00f3n m\u00e9dica y deben comenzar dentro de los primeros siete d\u00edas.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\" style=\"font-size:15px\">La FDA (Administraci\u00f3n de Medicamentos y Alimentos, por sus siglas en espa\u00f1ol) ha concedido la aprobaci\u00f3n total a uno y la autorizaci\u00f3n de uso de emergencia al segundo de los dos antivirales orales utilizados para tratar el COVID-19 en personas infectadas con el virus y <strong>que tienen un alto riesgo de desarrollar una enfermedad grave<\/strong>.\u00a0La FDA tambi\u00e9n aprob\u00f3 un antiviral intravenoso para el tratamiento de personas infectadas con el virus y que tienen un alto riesgo de desarrollar COVID-19 grave.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-7 wp-block-paragraph\" style=\"font-size:15px\">Seg\u00fan Proyecto de Educaci\u00f3n y Equidad en materia de Vacunas, los<strong> antivirales orales son m\u00e1s efectivos cuando se comienzan a administrar lo antes posible despu\u00e9s de la infecci\u00f3n<\/strong>. Adem\u00e1s, los ensayos cl\u00ednicos han demostrado que los antivirales orales reducen el riesgo de hospitalizaci\u00f3n o muerte hasta en un 88%. Una ventaja del tratamiento antiviral es que no se requiere una prueba positiva del virus para poder recetarlos, pero las personas deben consultar con su proveedor\u00a0de atenci\u00f3n m\u00e9dica si pueden recibirlos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8 wp-block-paragraph\" style=\"font-size:15px\"><strong>Los antivirales orales seguir\u00e1n siendo gratuitos para todos en los EE. UU. hasta que se agote el suministro distribuido a nivel federal.<\/strong> Despu\u00e9s de eso, los antivirales orales pasar\u00e1n a la cobertura de seguro tradicional.\u00a0Los costos variar\u00e1n seg\u00fan su plan de seguro, aunque las personas cubiertas por Medicaid seguir\u00e1n recibiendo antivirales orales de forma gratuita hasta al menos septiembre de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-9 wp-block-paragraph\" style=\"font-size:15px\"><strong><br>Fuente:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.who.int\/teams\/health-care-readiness\/covid-19\/therapeutics\">https:\/\/www.who.int\/teams\/health-care-readiness\/covid-19\/therapeutics<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/your-health\/treatments-for-severe-illness.html\">https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/your-health\/treatments-for-severe-illness.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/covidvaccineproject.org\/treatments\/\">https:\/\/covidvaccineproject.org\/treatments\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tres a\u00f1os de la pandemia del COVID-19 y a menos de un a\u00f1o de declarar el fin del virus como una emergencia de salud p\u00fablica de importancia internacional, no podemos dejar de considerar el virus como una amenaza para la salud mundial. El virus lleg\u00f3 para quedarse, y los pa\u00edses ahora deben integrar pr\u00e1cticas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9],"tags":[],"class_list":["post-13747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevos tratamientos antivirales contra el COVID-19 - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevos tratamientos antivirales contra el COVID-19 - NHCOA\" \/>\n<meta property=\"og:description\" content=\"A tres a\u00f1os de la pandemia del COVID-19 y a menos de un a\u00f1o de declarar el fin del virus como una emergencia de salud p\u00fablica de importancia internacional, no podemos dejar de considerar el virus como una amenaza para la salud mundial. El virus lleg\u00f3 para quedarse, y los pa\u00edses ahora deben integrar pr\u00e1cticas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-17T14:52:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T14:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Nuevos tratamientos antivirales contra el COVID-19\",\"datePublished\":\"2023-11-17T14:52:03+00:00\",\"dateModified\":\"2023-11-17T14:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/\"},\"wordCount\":706,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Blog-header-47.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/\",\"name\":\"Nuevos tratamientos antivirales contra el COVID-19 - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Blog-header-47.png\",\"datePublished\":\"2023-11-17T14:52:03+00:00\",\"dateModified\":\"2023-11-17T14:52:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/nuevos-tratamientos-antivirales-contra-el-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevos tratamientos antivirales contra el COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevos tratamientos antivirales contra el COVID-19 - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"Nuevos tratamientos antivirales contra el COVID-19 - NHCOA","og_description":"A tres a\u00f1os de la pandemia del COVID-19 y a menos de un a\u00f1o de declarar el fin del virus como una emergencia de salud p\u00fablica de importancia internacional, no podemos dejar de considerar el virus como una amenaza para la salud mundial. El virus lleg\u00f3 para quedarse, y los pa\u00edses ahora deben integrar pr\u00e1cticas [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/","og_site_name":"NHCOA","article_published_time":"2023-11-17T14:52:03+00:00","article_modified_time":"2023-11-17T14:52:05+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Nuevos tratamientos antivirales contra el COVID-19","datePublished":"2023-11-17T14:52:03+00:00","dateModified":"2023-11-17T14:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/"},"wordCount":706,"image":{"@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47.png","articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/","url":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/","name":"Nuevos tratamientos antivirales contra el COVID-19 - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2023\/11\/Blog-header-47.png","datePublished":"2023-11-17T14:52:03+00:00","dateModified":"2023-11-17T14:52:05+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/nuevos-tratamientos-antivirales-contra-el-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Nuevos tratamientos antivirales contra el COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13747"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13747\/revisions"}],"predecessor-version":[{"id":13748,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13747\/revisions\/13748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13745"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}