{"id":13950,"date":"2024-03-08T14:38:00","date_gmt":"2024-03-08T14:38:00","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=13950"},"modified":"2024-03-08T14:38:02","modified_gmt":"2024-03-08T14:38:02","slug":"los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/","title":{"rendered":"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76-1024x576.png\" alt=\"\" class=\"wp-image-13951\" style=\"width:550px\" srcset=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76-980x551.png 980w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"font-size:15px\">El 1 de marzo de 2024, los Centros para el Control de Enfermedades (CDC) <strong>publicaron una actualizaci\u00f3n de sus recomendaciones sobre la protecci\u00f3n y la gesti\u00f3n de COVID-19<\/strong>: ya no se recomienda un periodo de aislamiento de 5 d\u00edas para las personas que hayan obtenido un resultado positivo. En cambio, <strong>si el resultado de la prueba de COVID-19 es positivo, los CDC recomiendan ahora que se a\u00edsle s\u00f3lo hasta que se sienta bien de nuevo y haya pasado 24 horas sin fiebre.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\" style=\"font-size:15px\">Para algunos, esta actualizaci\u00f3n puede parecer emocionante y como si la amenaza de COVID-19 fuera menos peligrosa, pero no es as\u00ed. De hecho, estas actualizaciones <strong>simplemente reflejan la intenci\u00f3n de los CDC de prestar m\u00e1s atenci\u00f3n a las enfermedades respiratorias en su totalidad<\/strong>. Seg\u00fan la directora de los CDC, la Dra. Mandy Cohen, ahora hay menos hospitalizaciones y muertes debidas al COVID-19, y m\u00e1s que se deben a otras enfermedades respiratorias como la gripe y el VRS (virus respiratorio sincitial).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\" style=\"font-size:15px\">Es cierto que la prevenci\u00f3n del COVID-19 ha avanzado mucho. Gracias a la actualizaci\u00f3n de las vacunas y a la mejora de los tratamientos, el riesgo de enfermedad por COVID-19 ha disminuido, pero esto no debe tomarse como motivo para tom\u00e1rselo a la ligera. <strong>Debemos seguir teniendo en cuenta a las personas con mayor riesgo de contraer la enfermedad por COVID-19, como los adultos mayores y las personas inmunodeprimidas. Tenemos la responsabilidad de pensar en su bienestar, y no s\u00f3lo en nuestra propia conveniencia.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\" style=\"font-size:15px\">Los CDC siguen recomendando que, durante los 5 d\u00edas en los que estar\u00eda aislado, se tomen medidas responsables para la salud de los dem\u00e1s, como por ejemplo<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-size:15px\">Distanciamiento social<\/li>\n\n\n\n<li>Uso de una mascarilla bien ajustada<\/li>\n\n\n\n<li>Mayor pr\u00e1cticas de higiene, como lavarse las manos con frecuencia<\/li>\n\n\n\n<li>Buscar espacios al aire libre cuando sea posible<\/li>\n<\/ul>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\" style=\"font-size:15px\">Los CDC nos recuerdan que estas &#8220;<strong>precauciones son especialmente importantes para proteger a las personas con mayor riesgo de enfermedad grave, incluyendo los mayores de 65 a\u00f1os y las personas con sistemas inmunitarios debilitados<\/strong>.&#8221; Tambi\u00e9n afirman que los adultos mayores son 9 veces m\u00e1s propensos a morir debido a COVID-19 que las personas que tienen entre 18 y 39 a\u00f1os.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\" style=\"font-size:15px\">Adem\u00e1s, la Organizaci\u00f3n Mundial de la Salud tambi\u00e9n recomienda tomar las medidas descritas por los CDC para garantizar la seguridad de los dem\u00e1s en caso de resultado positivo. Sin embargo, en lo que respecta al autoaislamiento, la OMS sigue recomendando un periodo de 10 d\u00edas a partir de la aparici\u00f3n de los primeros s\u00edntomas.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-7 wp-block-paragraph\" style=\"font-size:15px\">En NHCOA sabemos muy bien que las necesidades de las personas menos favorecidas, como los adultos mayores y los inmunodeprimidos, no siempre se tienen en cuenta cuando se trata de normas y directrices destinadas al p\u00fablico en general. <strong>Invitamos a todos a tener en cuenta a estas personas: nuestros seres queridos, nuestros compa\u00f1eros de trabajo, los miembros de nuestra comunidad; todos ellos merecen que se les d\u00e9 prioridad por encima de la posible conveniencia de un periodo de aislamiento m\u00e1s corto.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8 wp-block-paragraph\" style=\"font-size:15px\"><strong>Sources:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">\u201cRespiratory Viruses and Older Adults,\u201d Respiratory Guidance. The Centers for Disease Control and Prevention. <a href=\"https:\/\/www.cdc.gov\/respiratory-viruses\/risk-factors\/older-adults.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.cdc.gov\/respiratory-viruses\/risk-factors\/older-adults.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">\u201cCDC Updates and Simplifies Respiratory Virus Recommendations,\u201d CDC Newsroom Releases. The Centers for Disease Control and Prevention. <a href=\"https:\/\/www.cdc.gov\/media\/releases\/2024\/p0301-respiratory-virus.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.cdc.gov\/media\/releases\/2024\/p0301-respiratory-virus.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">Edwards, Erika. \u201cCDC Updates Covid Isolation Guidelines for People Who Test Positive,\u201d Health News. NBC News. <a href=\"https:\/\/www.nbcnews.com\/health\/health-news\/covid-isolation-guidelines-cdc-positive-cases-updated-rcna141317\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nbcnews.com\/health\/health-news\/covid-isolation-guidelines-cdc-positive-cases-updated-rcna141317<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">\u201cAdvice for the Public,\u201d Coronavirus Disease (COVID-19). World Health Organization. <a href=\"https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019\/advice-for-public\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019\/advice-for-public<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 1 de marzo de 2024, los Centros para el Control de Enfermedades (CDC) publicaron una actualizaci\u00f3n de sus recomendaciones sobre la protecci\u00f3n y la gesti\u00f3n de COVID-19: ya no se recomienda un periodo de aislamiento de 5 d\u00edas para las personas que hayan obtenido un resultado positivo. En cambio, si el resultado de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9],"tags":[59,19],"class_list":["post-13950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-coronavirus","tag-covid-19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro - NHCOA\" \/>\n<meta property=\"og:description\" content=\"El 1 de marzo de 2024, los Centros para el Control de Enfermedades (CDC) publicaron una actualizaci\u00f3n de sus recomendaciones sobre la protecci\u00f3n y la gesti\u00f3n de COVID-19: ya no se recomienda un periodo de aislamiento de 5 d\u00edas para las personas que hayan obtenido un resultado positivo. En cambio, si el resultado de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T14:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T14:38:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro\",\"datePublished\":\"2024-03-08T14:38:00+00:00\",\"dateModified\":\"2024-03-08T14:38:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/\"},\"wordCount\":624,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Blog-header-76.png\",\"keywords\":[\"coronavirus\",\"covid-19\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/\",\"name\":\"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Blog-header-76.png\",\"datePublished\":\"2024-03-08T14:38:00+00:00\",\"dateModified\":\"2024-03-08T14:38:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/","og_locale":"en_US","og_type":"article","og_title":"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro - NHCOA","og_description":"El 1 de marzo de 2024, los Centros para el Control de Enfermedades (CDC) publicaron una actualizaci\u00f3n de sus recomendaciones sobre la protecci\u00f3n y la gesti\u00f3n de COVID-19: ya no se recomienda un periodo de aislamiento de 5 d\u00edas para las personas que hayan obtenido un resultado positivo. En cambio, si el resultado de la [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/","og_site_name":"NHCOA","article_published_time":"2024-03-08T14:38:00+00:00","article_modified_time":"2024-03-08T14:38:02+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro","datePublished":"2024-03-08T14:38:00+00:00","dateModified":"2024-03-08T14:38:02+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/"},"wordCount":624,"image":{"@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76.png","keywords":["coronavirus","covid-19"],"articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/","url":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/","name":"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/03\/Blog-header-76.png","datePublished":"2024-03-08T14:38:00+00:00","dateModified":"2024-03-08T14:38:02+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/los-cdc-actualizan-sus-directrices-sobre-el-covid-19-que-debemos-tener-en-cuenta-en-el-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Los CDC actualizan sus directrices sobre el COVID-19: Qu\u00e9 debemos tener en cuenta en el futuro"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=13950"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13950\/revisions"}],"predecessor-version":[{"id":13952,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/13950\/revisions\/13952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/13951"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=13950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=13950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=13950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}