{"id":14253,"date":"2024-09-05T21:12:20","date_gmt":"2024-09-05T21:12:20","guid":{"rendered":"https:\/\/nhcoa.org\/es\/?p=14253"},"modified":"2024-10-08T20:00:34","modified_gmt":"2024-10-08T20:00:34","slug":"empoderamiento-latino-dr-richard-carmona","status":"publish","type":"post","link":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/","title":{"rendered":"Empoderamiento Latino: Dr. Richard Carmona"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593-1024x576.png\" alt=\"\" class=\"wp-image-14251\" style=\"width:550px\" srcset=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593-980x551.png 980w, https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"font-size:15px\">El <strong>Dr. Richard Carmona<\/strong> es el <strong>17\u00ba Cirujano General del Servicio de Salud P\u00fablica de Estados Unidos<\/strong>, nombrado por George W. Bush en 2002. <strong>Antes de ocupar este importante cargo, tuvo una larga carrera profesional que se prolong\u00f3 durante d\u00e9cadas.<\/strong> Naci\u00f3 el 22 de noviembre de 1949 en Nueva York. Criado en el barrio espa\u00f1ol de Harlem, la familia de Carmona era de Puerto Rico, y con muy poca riqueza, su infancia estar\u00eda definida por la lucha, ya que su familia soport\u00f3 la falta de hogar, el hambre y las desigualdades en salud demasiado comunes en las familias pobres de Estados Unidos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\" style=\"font-size:15px\">Una vez alcanzada la mayor\u00eda de edad en 1967, Richard Carmona abandon\u00f3 el instituto para alistarse en el ej\u00e9rcito estadounidense. Recibi\u00f3 su Diploma de Equivalencia General del Ej\u00e9rcito, la primera iteraci\u00f3n del GED que se cre\u00f3 en 1942 para ayudar a los estadounidenses a ingresar en las fuerzas armadas, y con \u00e9l pudo alistarse en las Fuerzas Especiales del Ej\u00e9rcito. Fue destinado a Vietnam, donde entr\u00f3 en combate y se convirti\u00f3 en un veterano condecorado. Una vez que termin\u00f3 su servicio activo, regres\u00f3 a Nueva York y, gracias a su condici\u00f3n de veterano, pudo asistir al Bronx Community College, donde obtuvo su t\u00edtulo de asociado en artes. Despu\u00e9s de su t\u00edtulo de asociado, Carmona cruz\u00f3 el pa\u00eds para asistir a la Universidad de California, San Francisco, donde recibir\u00eda su licenciatura en Ciencias en 1977. <strong>Posteriormente asisti\u00f3 a la Facultad de Medicina de la Universidad de California, donde no s\u00f3lo se titul\u00f3 en Medicina, sino que recibi\u00f3 el bast\u00f3n de oro como mejor graduado de su promoci\u00f3n. El premio bast\u00f3n de oro se concede espec\u00edficamente a los graduados que ejemplifican las cualidades de un \u00abverdadero m\u00e9dico\u00bb.<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\" style=\"font-size:15px\">En una d\u00e9cada, el Dr. Richard Carmona hab\u00eda abandonado la escuela secundaria, hab\u00eda recorrido medio mundo y vuelto, y hab\u00eda salido del otro lado no con uno, sino con tres t\u00edtulos y una carrera completamente nueva. Su siguiente paso ser\u00eda <strong>en los Institutos Nacionales de Salud<\/strong>, centrada en traumatismos, quemaduras y cuidados intensivos. Tras una serie de logros educativos, Carmona lleg\u00f3 a Arizona, donde fue contratado por el Centro M\u00e9dico de Tucson y la Universidad de Arizona para crear y supervisar el primer sistema regional de traumatolog\u00eda del estado. Mientras ocupaba este cargo, el <strong>Dr. Richard Carmona tambi\u00e9n fue nombrado presidente del Sistema Regional de Emergencias M\u00e9dicas del Sur de Arizona y profesor de cirug\u00eda, salud p\u00fablica y medicina familiar y comunitaria en la Universidad de Arizona.<\/strong> Tambi\u00e9n fue designado cirujano y ayudante del sheriff del condado de Pima y miembro del Colegio Americano de Cirujanos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\" style=\"font-size:15px\"><strong>Carmona trabaj\u00f3 durante m\u00e1s de 34 a\u00f1os en el Departamento del Sheriff del Condado de Pima y, durante ese impresionante periodo de tiempo, se interesar\u00eda cada vez m\u00e1s por la salud p\u00fablica, a medida que iba adquiriendo conocimiento. <\/strong>Se dio cuenta de que la mayor\u00eda de las enfermedades y lesiones de sus pacientes eran evitables; estaban recibiendo una atenci\u00f3n reaccionaria, cuando deber\u00edan haber recibido una atenci\u00f3n preventiva.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\" style=\"font-size:15px\">En 2002, el Dr. Richard Carmona tuvo la oportunidad de cambiar las cosas a escala nacional. <strong>El Presidente George W. Bush propuso su candidatura como 17\u00ba Cirujano General de Estados Unidos, elogiando su experiencia en gesti\u00f3n de emergencias, bioterrorismo y aplicaci\u00f3n de la ley<\/strong>. Carmona asum\u00eda un cargo de inmensa magnitud en medio de un mundo reci\u00e9n salido del 11 de septiembre. Como Cirujano General, se centr\u00f3 especialmente en la atenci\u00f3n preventiva, las disparidades sanitarias y la alfabetizaci\u00f3n sanitaria. Su permanencia en el cargo se recuerda a menudo por su hist\u00f3rico informe sobre los peligros del fumador pasivo.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\" style=\"font-size:15px\">En 2006, el Dr. Richard Carmona complet\u00f3 su mandato reglamentario de cuatro a\u00f1os como Cirujano General. <strong>Fue la segunda persona de ascendencia puertorrique\u00f1a en asumir el cargo, y el primer hombre latino. <\/strong>Sus contribuciones a la atenci\u00f3n preventiva y a la siempre cambiante perspectiva nacional de la salud en Estados Unidos no pueden ponerse en duda, y aplaudimos la atenci\u00f3n del Dr. Carmona a la atenci\u00f3n preventiva y a la alfabetizaci\u00f3n sanitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-7 wp-block-paragraph\" style=\"font-size:15px\"><strong>Referencias:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Klein, Joan. Richard Carmona: A Surgeon General for Troubled Times. Emergency Medicine News 25(11):p 38, November 2003. https:\/\/journals.lww.com\/em-news\/fulltext\/2003\/11000\/richard_carmona__a_surgeon_general_for_troubled.21.aspx<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; &#8220;Carmona, Richard: 1949\u2014: U.S. Surgeon General .&#8221; Contemporary Hispanic Biography. . Encyclopedia.com. (August 16, 2024). https:\/\/www.encyclopedia.com\/education\/news-wires-white-papers-and-books\/carmona-richard-1949-us-surgeon-general<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; \u201cVice Admiral Richard H. Carmona [\u2026]\u201d George W. Bush, White House Archives. https:\/\/georgewbush-whitehouse.archives.gov\/government\/carmona-bio.html<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; \u201cRichard H. Carmona, M.D., M.P.H, FACS\u201d Richard H. Carmona Biography. Darmouth College. https:\/\/home.dartmouth.edu\/sites\/home\/files\/2023-09\/Carmona.pdf <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. Richard Carmona es el 17\u00ba Cirujano General del Servicio de Salud P\u00fablica de Estados Unidos, nombrado por George W. Bush en 2002. Antes de ocupar este importante cargo, tuvo una larga carrera profesional que se prolong\u00f3 durante d\u00e9cadas. Naci\u00f3 el 22 de noviembre de 1949 en Nueva York. Criado en el barrio espa\u00f1ol [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[9],"tags":[384,381,380,175,10,328,122,385],"class_list":["post-14253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-cirujano-general","tag-dr-carmona","tag-dr-richard-carmona","tag-empoderamiento","tag-empoderamiento-latino","tag-estados-unidos","tag-latino","tag-medico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empoderamiento Latino: Dr. Richard Carmona - NHCOA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empoderamiento Latino: Dr. Richard Carmona - NHCOA\" \/>\n<meta property=\"og:description\" content=\"El Dr. Richard Carmona es el 17\u00ba Cirujano General del Servicio de Salud P\u00fablica de Estados Unidos, nombrado por George W. Bush en 2002. Antes de ocupar este importante cargo, tuvo una larga carrera profesional que se prolong\u00f3 durante d\u00e9cadas. Naci\u00f3 el 22 de noviembre de 1949 en Nueva York. Criado en el barrio espa\u00f1ol [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/\" \/>\n<meta property=\"og:site_name\" content=\"NHCOA\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T21:12:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T20:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nhcoa_media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nhcoa_media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/\"},\"author\":{\"name\":\"nhcoa_media\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"headline\":\"Empoderamiento Latino: Dr. Richard Carmona\",\"datePublished\":\"2024-09-05T21:12:20+00:00\",\"dateModified\":\"2024-10-08T20:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/\"},\"wordCount\":816,\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Blog-header-2024-09-05T143404.593.png\",\"keywords\":[\"cirujano general\",\"dr. carmona\",\"dr. richard carmona\",\"empoderamiento\",\"Empoderamiento latino\",\"estados unidos\",\"Latino\",\"m\u00e9dico\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/\",\"name\":\"Empoderamiento Latino: Dr. Richard Carmona - NHCOA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Blog-header-2024-09-05T143404.593.png\",\"datePublished\":\"2024-09-05T21:12:20+00:00\",\"dateModified\":\"2024-10-08T20:00:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/empoderamiento-latino-dr-richard-carmona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empoderamiento Latino: Dr. Richard Carmona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/\",\"name\":\"NHCOA\",\"description\":\"Improving lives of hispanic and latino older adults.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/#\\\/schema\\\/person\\\/af97334cbd12a949fea7291405d4a890\",\"name\":\"nhcoa_media\",\"url\":\"https:\\\/\\\/nhcoa.org\\\/es\\\/author\\\/nhcoa_media\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empoderamiento Latino: Dr. Richard Carmona - NHCOA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/","og_locale":"en_US","og_type":"article","og_title":"Empoderamiento Latino: Dr. Richard Carmona - NHCOA","og_description":"El Dr. Richard Carmona es el 17\u00ba Cirujano General del Servicio de Salud P\u00fablica de Estados Unidos, nombrado por George W. Bush en 2002. Antes de ocupar este importante cargo, tuvo una larga carrera profesional que se prolong\u00f3 durante d\u00e9cadas. Naci\u00f3 el 22 de noviembre de 1949 en Nueva York. Criado en el barrio espa\u00f1ol [&hellip;]","og_url":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/","og_site_name":"NHCOA","article_published_time":"2024-09-05T21:12:20+00:00","article_modified_time":"2024-10-08T20:00:34+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593.png","type":"image\/png"}],"author":"nhcoa_media","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nhcoa_media","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/#article","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/"},"author":{"name":"nhcoa_media","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"headline":"Empoderamiento Latino: Dr. Richard Carmona","datePublished":"2024-09-05T21:12:20+00:00","dateModified":"2024-10-08T20:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/"},"wordCount":816,"image":{"@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593.png","keywords":["cirujano general","dr. carmona","dr. richard carmona","empoderamiento","Empoderamiento latino","estados unidos","Latino","m\u00e9dico"],"articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/","url":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/","name":"Empoderamiento Latino: Dr. Richard Carmona - NHCOA","isPartOf":{"@id":"https:\/\/nhcoa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/#primaryimage"},"image":{"@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/#primaryimage"},"thumbnailUrl":"https:\/\/nhcoa.org\/es\/wp-content\/uploads\/2024\/09\/Blog-header-2024-09-05T143404.593.png","datePublished":"2024-09-05T21:12:20+00:00","dateModified":"2024-10-08T20:00:34+00:00","author":{"@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890"},"breadcrumb":{"@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nhcoa.org\/es\/empoderamiento-latino-dr-richard-carmona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nhcoa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Empoderamiento Latino: Dr. Richard Carmona"}]},{"@type":"WebSite","@id":"https:\/\/nhcoa.org\/es\/#website","url":"https:\/\/nhcoa.org\/es\/","name":"NHCOA","description":"Improving lives of hispanic and latino older adults.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nhcoa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nhcoa.org\/es\/#\/schema\/person\/af97334cbd12a949fea7291405d4a890","name":"nhcoa_media","url":"https:\/\/nhcoa.org\/es\/author\/nhcoa_media\/"}]}},"_links":{"self":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/14253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/comments?post=14253"}],"version-history":[{"count":1,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/14253\/revisions"}],"predecessor-version":[{"id":14254,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/posts\/14253\/revisions\/14254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media\/14251"}],"wp:attachment":[{"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/media?parent=14253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/categories?post=14253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nhcoa.org\/es\/wp-json\/wp\/v2\/tags?post=14253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}